{"id":651,"date":"2010-12-07T14:39:55","date_gmt":"2010-12-07T13:39:55","guid":{"rendered":"http:\/\/www.lautoentrepreneur.net\/?p=651"},"modified":"2010-12-07T14:39:55","modified_gmt":"2010-12-07T13:39:55","slug":"cfe-les-auto-entrepreneurs-finalement-exoneres-pendant-3-ans","status":"publish","type":"post","link":"https:\/\/lautoentrepreneur.net\/index.php\/2010\/12\/07\/cfe-les-auto-entrepreneurs-finalement-exoneres-pendant-3-ans\/","title":{"rendered":"CFE : Les auto-entrepreneurs finalement exon\u00e9r\u00e9s pendant 3 ans"},"content":{"rendered":"<p><strong>Le S\u00e9nat, sur proposition du gouvernement, a vot\u00e9 lundi, dans le cadre du projet de budget pour 2011, l&rsquo;exon\u00e9ration pour les auto-entrepreneurs de la cotisation fonci\u00e8re des entreprises (CFE), qui remplace la taxe professionnelle depuis le 1er janvier 2010.<\/strong><\/p>\n<p>Les s\u00e9nateurs ont donc finalement adopt\u00e9 un sous-amendement pr\u00e9sent\u00e9 par le ministre du Budget, Fran\u00e7ois Baroin, exemptant de la <strong>CFE <\/strong>pendant trois ans tous les auto-entrepreneurs. C&rsquo;est une tr\u00e8s bonne nouvelle pour ces derniers apr\u00e8s des semaines de pol\u00e9mique qui n&rsquo;avaient cess\u00e9 d&rsquo;enfler apr\u00e8s que les premiers <a href=\"http:\/\/www.lautoentrepreneur.net\/2010\/11\/avez-vous-recu-lavis-dimposition-cotisation-fonciere-des-entreprises\/\">avis d&rsquo;imposition pour la CFE<\/a> aient \u00e9t\u00e9 re\u00e7us.<\/p>\n<p>Bercy avait annonc\u00e9 mardi dernier que le gouvernement allait prendre cette disposition apr\u00e8s que de nombreux auto-entrepreneurs se soient plaints de devoir payer la <strong>CFE <\/strong>alors qu&rsquo;ils r\u00e9alisent peu voire pas de chiffre d&rsquo;affaires.<\/p>\n<p>Ils s&rsquo;\u00e9taient \u00e9galement plaints de devoir payer une cotisation \u00ab\u00a0trop \u00e9lev\u00e9e, sans rapport avec leur niveau d&rsquo;activit\u00e9\u00a0\u00bb. Cette cotisation, fix\u00e9e par les communes, est en effet calcul\u00e9e sur la base de la <strong>valeur locative<\/strong> du lieu de travail des auto-entrepreneurs en sachant que dans la plupart des cas il s&rsquo;agit en fait de leur <strong>domicile<\/strong>.<\/p>\n<p>Mais sur ce dernier point, le gouvernement n&rsquo;a \u00e0 ce jour rien annonc\u00e9 de pr\u00e9cis. Celui-ci a su se donner un peu d&rsquo;air avant de revoir (peut-\u00eatre ?) le mode de calcul de cette taxe.<\/p>\n<p><strong>Herv\u00e9 Novelli<\/strong>, ancien secr\u00e9taire d&rsquo;Etat charg\u00e9 des PME, s&rsquo;est d&rsquo;ailleurs r\u00e9cemment exprim\u00e9 sur ce sujet. Il a ainsi reconnu qu'\u00a0\u00bbil reste un probl\u00e8me, ce sont les auto-entrepreneurs qui d\u00e9veloppent un petit revenu, un petit chiffre d&rsquo;affaires et qui vont quand m\u00eame \u00eatre <strong>tax\u00e9s <\/strong>au titre de cette contribution fonci\u00e8re\u00a0\u00bb.<\/p>\n<p>\u00abNous avions instaur\u00e9 une suppression de la taxe professionnelle pour les petits revenus\u00bb, a-t-il rappel\u00e9. \u00abIl faut faire la m\u00eame chose\u00bb avec la CFE \u00ab et il faudra que le Parlement l\u00e9gif\u00e8re dans ce domaine\u00a0\u00bb. L&rsquo;ex-secr\u00e9taire d&rsquo;Etat charg\u00e9 des PME s&rsquo;est d\u00e9clar\u00e9 convaincu que la Parlement fera la m\u00eame chose que ce qu&rsquo;il avait fait hier pour la taxe professionnelle.<\/p>\n<p id=\"blogonetVote\">\n\t\t<a href=\"http:\/\/tools.blogonet.fr\/article.php?url=https%3A%2F%2Flautoentrepreneur.net%2Findex.php%2F2010%2F12%2F07%2Fcfe-les-auto-entrepreneurs-finalement-exoneres-pendant-3-ans%2F\" >\n\t\t\t<img decoding=\"async\" src=\"http:\/\/tools.blogonet.fr\/article.php?url=https%3A%2F%2Flautoentrepreneur.net%2Findex.php%2F2010%2F12%2F07%2Fcfe-les-auto-entrepreneurs-finalement-exoneres-pendant-3-ans%2F&image\" alt=\"Voter !\" title=\"Voter pour cet article, sur Blogonet\" \/>\n\t\t<\/a>\n\t<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Le S\u00e9nat, sur proposition du gouvernement, a vot\u00e9 lundi, dans le cadre du projet de budget pour 2011, l&rsquo;exon\u00e9ration pour les auto-entrepreneurs de la cotisation <a class=\"mh-excerpt-more\" href=\"https:\/\/lautoentrepreneur.net\/index.php\/2010\/12\/07\/cfe-les-auto-entrepreneurs-finalement-exoneres-pendant-3-ans\/\" title=\"CFE : Les auto-entrepreneurs finalement exon\u00e9r\u00e9s pendant 3 ans\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-651","post","type-post","status-publish","format-standard","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts\/651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/comments?post=651"}],"version-history":[{"count":0,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts\/651\/revisions"}],"wp:attachment":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/media?parent=651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/categories?post=651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/tags?post=651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}