{"id":602,"date":"2010-11-11T11:53:09","date_gmt":"2010-11-11T10:53:09","guid":{"rendered":"http:\/\/www.lautoentrepreneur.net\/?p=602"},"modified":"2010-11-11T11:53:09","modified_gmt":"2010-11-11T10:53:09","slug":"avez-vous-recu-lavis-dimposition-cotisation-fonciere-des-entreprises","status":"publish","type":"post","link":"https:\/\/lautoentrepreneur.net\/index.php\/2010\/11\/11\/avez-vous-recu-lavis-dimposition-cotisation-fonciere-des-entreprises\/","title":{"rendered":"Avez-vous re\u00e7u l&rsquo;avis d&rsquo;imposition Cotisation Fonci\u00e8re des Entreprises ?"},"content":{"rendered":"<p>Si vous avez cr\u00e9\u00e9 votre auto-entreprise en 2009 et que vous n&rsquo;avez pas opt\u00e9 pour le versement lib\u00e9ratoire de l&rsquo;imp\u00f4t sur le revenu, vous \u00eates redevable cette ann\u00e9e de la <strong>contribution \u00e9conomique territoriale<\/strong> (CET) dans les m\u00eames conditions que les autres entreprises.<\/p>\n<h4>Un petit rappel sur la Contribution Economique Territoriale (CET)<\/h4>\n<p>La <strong>CET <\/strong>remplace, depuis le 1er janvier 2010, la taxe professionnelle. Cette contribution est compos\u00e9e de la <strong>cotisation fonci\u00e8re des entreprises<\/strong> (CFE) et de la <strong>cotisation sur la valeur ajout\u00e9e des entreprises<\/strong> (CVAE).<\/p>\n<h4>La Cotisation Fonci\u00e8re des Entreprises (CFE)<\/h4>\n<p>Concernant la <strong>CFE<\/strong>, son montant varie selon la valeur locative des biens fonciers utilis\u00e9s par l&rsquo;entreprise. Mais une cotisation minimale est exig\u00e9e et sa base d&rsquo;imposition est fix\u00e9e par le conseil municipal. Mais sachez que le montant de cette cotisation minimale peut \u00eatre comprise entre entre 200 et 2 000 \u20ac !<\/p>\n<p>Pr\u00e9cisions \u00e9galement que la <strong>cotisation fonci\u00e8re des entreprise<\/strong>s (CFE) est assise sur la valeur locative des biens soumis \u00e0 la taxe fonci\u00e8re dont dispose le professionnel <strong>au 1er janvier de l\u2019ann\u00e9e d\u2019imposition<\/strong>. Il s\u2019agit de la valeur locative des locaux professionnels telle qu\u2019elle figure sur l\u2019avis d\u2019imposition \u00e0 la taxe professionnelle 2009. <\/p>\n<h4>La Cotisation sur la Valeur Ajout\u00e9e des Entreprises (CVAE)<\/h4>\n<p>Concernant la <strong>CVAE<\/strong>, les auto-entrepreneurs n&rsquo;ont ni \u00e0 l&rsquo;acquitter, ni \u00e0 la d\u00e9clarer, car cette cotisation est due par les entreprises dont le chiffre d&rsquo;affaires d\u00e9passe 152 500 \u20ac bien au del\u00e0 donc des limites de chiffres d&rsquo;affaires impos\u00e9es aux auto-entrepreneurs.<\/p>\n<p><strong>Dans la pratique donc, les auto-entrepreneurs ne sont donc redevables que de la cotisation fonci\u00e8re des entreprises (CFE).<\/strong><\/p>\n<h4>A combien s&rsquo;\u00e9l\u00e8ve la Cotisation Fonci\u00e8re des Entreprises pour 2010 ?<\/h4>\n<p>Il n&rsquo;y a pas qu&rsquo;une r\u00e9ponse \u00e0 cette question. En effet, la <strong>CFE <\/strong>est due par tous les professionnels quel que soit le montant de leur chiffre de recettes et leur r\u00e9gime d\u2019imposition sauf en cas d\u2019exon\u00e9ration permanente. Et le montant lui-m\u00eame d\u00e9pend de la commune (ou de la communaut\u00e9 de communes) o\u00f9 vous habitez comme on l&rsquo;a vu plus haut et va donc varier d\u2019une commune \u00e0 l\u2019autre.<\/p>\n<p>Vous avez peut-\u00eatre re\u00e7u dans votre bo\u00eete aux lettres votre avis d&rsquo;imposition pour la <strong>Cotisation Fonci\u00e8re des Entreprises<\/strong> pour l&rsquo;ann\u00e9e 2010. <strong>A combien s&rsquo;\u00e9l\u00e8ve le montant de votre imp\u00f4t ? <\/strong><\/p>\n<p>Les r\u00e9ponses \u00e0 cette question vont int\u00e9resser les auto-entrepreneurs b\u00e9n\u00e9ficiant de l&rsquo;exon\u00e9ration de la <strong>CET <\/strong>l&rsquo;ann\u00e9e de cr\u00e9ation de l&rsquo;entreprise et les deux ann\u00e9es civiles suivantes et qui se demandent combien ils vont devoir payer une fois qu&rsquo;ils ne pourront plus b\u00e9n\u00e9ficier de  cette exon\u00e9ration.<\/p>\n<h4>A combien s&rsquo;\u00e9l\u00e8ve le montant de votre Cotisation Fonci\u00e8re des Entreprises ?<\/h4>\n<p>Je propose donc aux auto-entrepreneurs qui ont re\u00e7u leur avis d&rsquo;imposition de laisser en commentaire le montant de leur imp\u00f4t en pr\u00e9cisant la commune et le d\u00e9partement du lieu d&rsquo;imposition. Cela me permettra de constituer une base de donn\u00e9es que je vais actualiser et mettre \u00e0 disposition sur le site.<\/p>\n<p><strong>Merci d&rsquo;avance \u00e0 tous pour votre participation ! <\/strong><\/p>\n<p><strong><blink><u>Edit du 15\/11\/2010<\/u><\/blink><\/strong><\/p>\n<p><strong><em>Pour les auto-entrepreneurs qui ont opt\u00e9 pour le pr\u00e9l\u00e8vement fiscal lib\u00e9ratoire et qui ont re\u00e7u l&rsquo;avis d&rsquo;imposition pour la CFE, je ne peux que leur conseiller de contacter l&rsquo;URSSAF pour obtenir une copie de leur d\u00e9claration de d\u00e9but d&rsquo;activit\u00e9 et de la transmettre \u00e0 leur centre des imp\u00f4ts comme Djibey l&rsquo;a fait (voir son commentaire). Pour ceux-l\u00e0, il y a manifestement eu une erreur d&rsquo;appr\u00e9ciation de la part de l&rsquo;administration fiscale.<\/em><\/strong><\/p>\n<p>Pour les autres qui n&rsquo;ont pas opt\u00e9 pour le pr\u00e9l\u00e8vement fiscal lib\u00e9ratoire, la situation est plus d\u00e9licate. Car ils ont h\u00e9las la loi contre eux quelle que soit a priori leur situation (pas de CA d\u00e9clar\u00e9, pas de local professionnel, activit\u00e9 non s\u00e9dentaire). Je vous conseille donc d&rsquo;aller voir votre centre des imp\u00f4ts comme h\u00e9l\u00e8ne l&rsquo;a fait (voir \u00e9galement son commentaire) et d&rsquo;expliquer votre situation en esp\u00e9rant qu&rsquo;une demande de remise gracieuse pourra vous \u00eatre accord\u00e9e. <\/p>\n<p>On peut aussi esp\u00e9rer que les f\u00e9d\u00e9rations et associations qui repr\u00e9sentent les auto-entrepreneurs se mobilisent sur ce probl\u00e8me et interviennent aupr\u00e8s des responsables politiques afin de trouver une solution. Je vous invite donc aussi \u00e0 leur \u00e9crire ou \u00e0 les contacter pour leur expliquer cette situation inacceptable. Voici la liste des principales : <a href=\"http:\/\/www.union-auto-entrepreneurs.com\/\">UAE<\/a>, <a href=\"http:\/\/www.federation-auto-entrepreneur.fr\">fedae <\/a>, <a href=\"http:\/\/www.planete-auto-entrepreneur.com\/\">Plan\u00e8te Auto-Entrepreneur<\/a>.<\/p>\n<p><strong><blink><u>Edit du 17\/11\/2010<\/u><\/blink><\/strong><\/p>\n<p>Ca bouge du c\u00f4t\u00e9 de la F\u00e9d\u00e9ration des Auto-Entrepreneurs qui vient de reprendre sur son site cet article. Vous pouvez consulter la page en question en cliquant >>><a href=\"http:\/\/www.federation-auto-entrepreneur.fr\/actualites\/federation\/17112010\/auto-entrepreneurs-r%C3%A9clament-bouclier-fiscal\" target=\"_blank\">ici<\/a><<<.\n\nLa F\u00e9d\u00e9ration des Auto-Entrepreneurs r\u00e9clame la suppression de la CFE pour les auto-entrepreneurs n\u2019ayant r\u00e9alis\u00e9 aucun chiffre d\u2019affaires ! Et la F\u00e9d\u00e9ration des Auto-Entrepreneurs va plus loin et r\u00e9clame le b\u00e9n\u00e9fice du bouclier fiscal pour les auto-entrepreneurs en consid\u00e9rant l'ensemble des charges et des taxes auxquels ils sont actuellement soumis dans un exemple tr\u00e8s parlant.\n\nVoici le message que vient de m'envoyer Gr\u00e9goire Leclercq pr\u00e9sident de la F\u00e9d\u00e9ration des Auto-Entrepreneurs en r\u00e9ponse \u00e0 l'email d'alerte que je lui ai adress\u00e9 :\n\n<em>Nous sommes en pleine consultation sur ce sujet, et nous agissons vite&#8230;<br \/>\nRDV pris avec le ministre sur ce sujet.<\/em><\/p>\n<p>Tout espoir n&rsquo;est donc pas perdu pour ceux qui n&rsquo;ont pas opt\u00e9 pour le pr\u00e9l\u00e8vement fiscal lib\u00e9ratoire. <strong>Pour les autres, la consigne est claire : il ne faut pas payer la CFE<\/strong> !<\/p>\n<p><strong><blink><u>Edit du 23\/11\/2010<\/u><\/blink><\/strong><\/p>\n<p>La F\u00e9d\u00e9ration des Auto-Entrepreneurs a mis en ligne une lettre ouverte destin\u00e9e \u00e0 <strong>Fr\u00e9d\u00e9ric Lefebvre<\/strong>. Gr\u00e9goire Leclercq son pr\u00e9sident doit d&rsquo;ailleurs le rencontrer dans les prochains jours pour aborder cette regrettable situation et voir avec lui quelles mesures et am\u00e9nagements peuvent \u00eatre prises pour l&rsquo;ann\u00e9e 2010.<\/p>\n<p>Dans cette lettre, la F\u00e9d\u00e9ration r\u00e9clame :<\/p>\n<ul>\n<li>\nLa suppression de la CFE pour les auto-entrepreneurs n\u2019ayant r\u00e9alis\u00e9 aucun chiffre d\u2019affaires.<\/li>\n<li>\nLe plafonnement de la CFE pour les auto-entreprises ayant r\u00e9alis\u00e9 un chiffre d&rsquo;affaires.<\/li>\n<\/ul>\n<p>Vous pouvez vous aussi signer cette lettre afin de lui donner plus de poids \u00e0 l&rsquo;approche de ce prochain rendez-vous crucial pour de nombreux auto-entrepreneurs en situation d\u00e9licate.<\/p>\n<p align=\"center\">\n<a href=\"http:\/\/www.federation-auto-entrepreneur.fr\/lettre-ouverte-%C3%A0-monsieur-fr%C3%A9d%C3%A9ric-lefebvre\"><strong>Oui, je veux signer la lettre ouverte \u00e0 Fr\u00e9d\u00e9ric Lefebvre<\/strong><\/a><\/p>\n<p id=\"blogonetVote\">\n\t\t<a href=\"http:\/\/tools.blogonet.fr\/article.php?url=https%3A%2F%2Flautoentrepreneur.net%2Findex.php%2F2010%2F11%2F11%2Favez-vous-recu-lavis-dimposition-cotisation-fonciere-des-entreprises%2F\" >\n\t\t\t<img decoding=\"async\" src=\"http:\/\/tools.blogonet.fr\/article.php?url=https%3A%2F%2Flautoentrepreneur.net%2Findex.php%2F2010%2F11%2F11%2Favez-vous-recu-lavis-dimposition-cotisation-fonciere-des-entreprises%2F&image\" alt=\"Voter !\" title=\"Voter pour cet article, sur Blogonet\" \/>\n\t\t<\/a>\n\t<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Si vous avez cr\u00e9\u00e9 votre auto-entreprise en 2009 et que vous n&rsquo;avez pas opt\u00e9 pour le versement lib\u00e9ratoire de l&rsquo;imp\u00f4t sur le revenu, vous \u00eates <a class=\"mh-excerpt-more\" href=\"https:\/\/lautoentrepreneur.net\/index.php\/2010\/11\/11\/avez-vous-recu-lavis-dimposition-cotisation-fonciere-des-entreprises\/\" title=\"Avez-vous re\u00e7u l&rsquo;avis d&rsquo;imposition Cotisation Fonci\u00e8re des Entreprises ?\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[57,58,78,82,95,300],"class_list":["post-602","post","type-post","status-publish","format-standard","hentry","category-actualites","category-informations-pratiques","tag-cet","tag-cfe","tag-contribution-economique-territoriale","tag-cotisation-fonciere-des-entreprises","tag-cvae","tag-taxe-professionnelle"],"_links":{"self":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts\/602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/comments?post=602"}],"version-history":[{"count":0,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts\/602\/revisions"}],"wp:attachment":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/media?parent=602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/categories?post=602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/tags?post=602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}