{"id":295,"date":"2010-05-01T11:38:47","date_gmt":"2010-05-01T10:38:47","guid":{"rendered":"http:\/\/www.lautoentrepreneur.net\/?p=295"},"modified":"2010-05-01T11:38:47","modified_gmt":"2010-05-01T10:38:47","slug":"auto-entrepreneurs-attention-au-salariat-deguise","status":"publish","type":"post","link":"https:\/\/lautoentrepreneur.net\/index.php\/2010\/05\/01\/auto-entrepreneurs-attention-au-salariat-deguise\/","title":{"rendered":"Auto-Entrepreneurs : Attention au salariat d\u00e9guis\u00e9"},"content":{"rendered":"<p>Le <strong>r\u00e9gime de l&rsquo;auto-entrepreneur<\/strong> conna\u00eet un succ\u00e8s croissant, c&rsquo;est \u00e9vident. Mais les entreprises qui ont recours \u00e0 des auto-entrepreneurs doivent n\u00e9anmoins faire attention \u00e0 ne pas abuser de ce nouveau r\u00e9gime et placer les auto-entrepreneurs dans une situation de \u00ab\u00a0<strong>salariat d\u00e9guis\u00e9<\/strong>\u00ab\u00a0.<\/p>\n<p>En cas de litige entre l&rsquo;entreprise et l&rsquo;auto-entrepreneur mais aussi en cas de contr\u00f4le de l&rsquo;URSSAF, ce sera \u00e0 l\u2019entreprise (le donneur d\u2019ordre) de prouver qu&rsquo;il n\u2019y a pas \u00ab\u00a0<strong>salariat d\u00e9guis\u00e9<\/strong>\u00ab\u00a0.<\/p>\n<p>En effet, si l\u2019auto-entrepreneur est plac\u00e9, dans les faits, dans la m\u00eame situation qu\u2019un salari\u00e9, il peut solliciter <strong>la requalification de son contrat<\/strong> le liant \u00e0 l\u2019entreprise <strong>en contrat de travail<\/strong> et l\u2019URSSAF sera en droit de redemander la r\u00e9gularisation des cotisations \u00e0 hauteur du r\u00e9gime salari\u00e9. <\/p>\n<p>Ce sera le cas par exemple si :<\/p>\n<ul>\n<li>\nl\u2019auto-entrepreneur est sous la responsabilit\u00e9 d&rsquo;un seul employeur,<\/li>\n<\/ul>\n<p>Mais aussi si :<\/p>\n<ul>\n<li>\nil utilise les locaux et le mat\u00e9riel mis \u00e0 disposition par ce dernier (machine, v\u00e9hicule, etc),<\/li>\n<li>\nil respecte des horaires impos\u00e9s par l&rsquo;entreprise ou des tourn\u00e9es (cas du transport),<\/li>\n<li>\nil suit les r\u00e8gles impos\u00e9es dans l&rsquo;entreprise,<\/li>\n<li>\nil applique des tarifs d\u00e9finis par l&#8217;employeur,<\/li>\n<\/ul>\n<p>Devant le vide juridique, la jurisprudence r\u00e9cente a caract\u00e9ris\u00e9 <strong>le lien de subordination<\/strong> par l\u2019ex\u00e9cution d\u2019un travail sous l\u2019autorit\u00e9 d\u2019un employeur qui a pouvoir de donner des ordres et des directives, d\u2019en contr\u00f4ler l\u2019ex\u00e9cution et de sanctionner les manquements de son subordonn\u00e9.<\/p>\n<p>Les cons\u00e9quences financi\u00e8res peuvent se r\u00e9v\u00e9ler tr\u00e8s lourdes pour l\u2019entreprise, qui risque notamment de se voir reprocher de recourir au <strong>travail dissimul\u00e9<\/strong>.<\/p>\n<p>Auto-entrepreneurs concern\u00e9s par cet \u00e9tat de fait qui est tout simplement un abus de l&rsquo;application du <strong>r\u00e9gime de l&rsquo;auto-entrepreneur<\/strong>, je ne peux que vous conseillez avant d&rsquo;entreprendre une action aupr\u00e8s des Prudhommes d&rsquo;en parler avec votre client\/employeur afin que celui-ci mesure bien les cons\u00e9quences d&rsquo;une telle situation.<\/p>\n<p>Dans une <a href=\"http:\/\/www.lautoentrepreneur.net\/2010\/04\/auto-entrepreneur-du-salariat-a-la-prestation-de-services\/\">interview r\u00e9cente<\/a> accord\u00e9e par Herv\u00e9 Novelli, Secr\u00e9taire d&rsquo;Etat aux PME a indiqu\u00e9 que \u00ab\u00a0Pour \u00e9viter des abus, les services de contr\u00f4le (URSSAF, inspection du travail) sont extr\u00eamement vigilants et le seront plus encore \u00e0 l\u2019avenir : ils n\u2019h\u00e9siteront pas \u00e0 requalifier en contrats de travail des prestations de service d\u2019auto-entrepreneur qui correspondraient en fait \u00e0 une activit\u00e9 salariale.\u00a0\u00bb<\/p>\n<p id=\"blogonetVote\">\n\t\t<a href=\"http:\/\/tools.blogonet.fr\/article.php?url=https%3A%2F%2Flautoentrepreneur.net%2Findex.php%2F2010%2F05%2F01%2Fauto-entrepreneurs-attention-au-salariat-deguise%2F\" >\n\t\t\t<img decoding=\"async\" src=\"http:\/\/tools.blogonet.fr\/article.php?url=https%3A%2F%2Flautoentrepreneur.net%2Findex.php%2F2010%2F05%2F01%2Fauto-entrepreneurs-attention-au-salariat-deguise%2F&image\" alt=\"Voter !\" title=\"Voter pour cet article, sur Blogonet\" \/>\n\t\t<\/a>\n\t<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Le r\u00e9gime de l&rsquo;auto-entrepreneur conna\u00eet un succ\u00e8s croissant, c&rsquo;est \u00e9vident. Mais les entreprises qui ont recours \u00e0 des auto-entrepreneurs doivent n\u00e9anmoins faire attention \u00e0 ne <a class=\"mh-excerpt-more\" href=\"https:\/\/lautoentrepreneur.net\/index.php\/2010\/05\/01\/auto-entrepreneurs-attention-au-salariat-deguise\/\" title=\"Auto-Entrepreneurs : Attention au salariat d\u00e9guis\u00e9\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[9,271,306,314],"class_list":["post-295","post","type-post","status-publish","format-standard","hentry","category-informations-pratiques","tag-abus","tag-salariat-deguise","tag-travail-dissimule","tag-urssaf"],"_links":{"self":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts\/295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/comments?post=295"}],"version-history":[{"count":0,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts\/295\/revisions"}],"wp:attachment":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/media?parent=295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/categories?post=295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/tags?post=295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}