{"id":150,"date":"2009-09-23T10:37:11","date_gmt":"2009-09-23T09:37:11","guid":{"rendered":"http:\/\/www.lautoentrepreneur.net\/?p=150"},"modified":"2009-09-23T10:37:11","modified_gmt":"2009-09-23T09:37:11","slug":"ae-premier-bilan-apres-6-mois-dactivite","status":"publish","type":"post","link":"https:\/\/lautoentrepreneur.net\/index.php\/2009\/09\/23\/ae-premier-bilan-apres-6-mois-dactivite\/","title":{"rendered":"AE : Premier bilan apr\u00e8s 6 mois d&rsquo;activit\u00e9"},"content":{"rendered":"<p>Le site TPE-PME.com publie un article tr\u00e8s int\u00e9ressant sur un <a href=\"http:\/\/www.tpe-pme.com\/creation\/creation\/news\/9080-auto-entrepreneurs-premier-bilan-en-demi-teinte.php\" target=\"_blank\"><strong>premier bilan d&rsquo;activit\u00e9<\/strong><\/a> apr\u00e8s les 6 premiers mois d&rsquo;existence du statut de l&rsquo;<strong>auto-entrepreneur<\/strong>.<\/p>\n<p>Qu&rsquo;en ressort-il comme principales constatations :<\/p>\n<ul>\n<li>\nle chiffre d&rsquo;affaires a \u00e9t\u00e9 de <strong>4 700 euros<\/strong> en moyenne pour le 1<sup>er<\/sup> trimestre soit en extrapolant un peu un chiffre d&rsquo;affaires de pr\u00e8s 20 000 euros par an\n<\/li>\n<li>\nseuls <strong>4 auto-entrepreneurs sur 10<\/strong> ont finalement d\u00e9clar\u00e9 une activit\u00e9 jusqu&rsquo;\u00e0 fin juin (soit 6 sur 10 qui n&rsquo;ont d\u00e9clar\u00e9 aucun chiffre d&rsquo;affaires)\n<\/li>\n<li>\nLes chiffres montrent une mont\u00e9e en puissance du r\u00e9gime de l&rsquo;auto-entreprise : 54 millions d&rsquo;euros ont \u00e9t\u00e9 d\u00e9clar\u00e9s au titre du premier trimestre et 126 millions d&rsquo;euros au titre du deuxi\u00e8me trimestre.\n<\/li>\n<\/ul>\n<p>M\u00eame s&rsquo;il n&rsquo;est pas encore l&rsquo;heure de faire un premier bilan (un bilan classique d&rsquo;entreprise se fait au bout d&rsquo;un an), il n&rsquo;en demeure pas moins qu&rsquo;un tel montant de CA (environ 20000 euros par an) montre que les activit\u00e9s cr\u00e9\u00e9es sous le <strong>statut de l&rsquo;auto-entrepreneur<\/strong> sont en majorit\u00e9 des activit\u00e9s d&rsquo;appoint et non une activit\u00e9 principale. Rappelons aussi que nous parlons ici de chiffres d&rsquo;affaires et non de r\u00e9sultat brut et encore moins net !<\/p>\n<p>Et qu&rsquo;en est-il pour ceux d&rsquo;entre vous qui se sont lanc\u00e9s dans l&rsquo;<strong>auto-entreprise<\/strong> ? Quelles sont vos impressions sur ce statut et sur votre activit\u00e9 en tant qu&rsquo;<strong>auto-entrepreneur<\/strong> ? Est-ce votre activit\u00e9 principale ou une activit\u00e9 de compl\u00e9ment ?<\/p>\n<p id=\"blogonetVote\">\n\t\t<a href=\"http:\/\/tools.blogonet.fr\/article.php?url=https%3A%2F%2Flautoentrepreneur.net%2Findex.php%2F2009%2F09%2F23%2Fae-premier-bilan-apres-6-mois-dactivite%2F\" >\n\t\t\t<img decoding=\"async\" src=\"http:\/\/tools.blogonet.fr\/article.php?url=https%3A%2F%2Flautoentrepreneur.net%2Findex.php%2F2009%2F09%2F23%2Fae-premier-bilan-apres-6-mois-dactivite%2F&image\" alt=\"Voter !\" title=\"Voter pour cet article, sur Blogonet\" \/>\n\t\t<\/a>\n\t<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Le site TPE-PME.com publie un article tr\u00e8s int\u00e9ressant sur un premier bilan d&rsquo;activit\u00e9 apr\u00e8s les 6 premiers mois d&rsquo;existence du statut de l&rsquo;auto-entrepreneur. Qu&rsquo;en ressort-il <a class=\"mh-excerpt-more\" href=\"https:\/\/lautoentrepreneur.net\/index.php\/2009\/09\/23\/ae-premier-bilan-apres-6-mois-dactivite\/\" title=\"AE : Premier bilan apr\u00e8s 6 mois d&rsquo;activit\u00e9\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[16,64],"class_list":["post-150","post","type-post","status-publish","format-standard","hentry","category-actualites","tag-activite-auto-entrepreneur","tag-chiffre-daffaires"],"_links":{"self":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/comments?post=150"}],"version-history":[{"count":0,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/posts\/150\/revisions"}],"wp:attachment":[{"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/media?parent=150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/categories?post=150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lautoentrepreneur.net\/index.php\/wp-json\/wp\/v2\/tags?post=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}